{"id":170208,"date":"2025-02-13T17:25:35","date_gmt":"2025-02-13T16:25:35","guid":{"rendered":"https:\/\/www.tabakversand.ch\/?post_type=product&#038;p=170208"},"modified":"2026-06-15T14:09:24","modified_gmt":"2026-06-15T12:09:24","slug":"grinder-super-heroes-noir-2-pieces","status":"publish","type":"product","link":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/","title":{"rendered":"Grinder Super Heroes noir 2 pi\u00e8ces"},"content":{"rendered":"<p>Grinder Super Heroes noir 2 pi\u00e8ces<\/p>\n<p>&nbsp;<\/p>\n<table style=\"width: 361px;\" border=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 273px;\">mat\u00e9riel<\/td>\n<td style=\"width: 76px;\">m\u00e9tal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 273px;\">nombre de composants<\/td>\n<td style=\"width: 76px;\">2 parties<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 273px;\">diam\u00e8tre en mm<\/td>\n<td style=\"width: 76px;\">30<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 273px;\">hauteur en mm<\/td>\n<td style=\"width: 76px;\">15<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Tous les prix indiqu\u00e9s sont valables uniquement pour les commandes en ligne, TVA incluse, et peuvent \u00eatre modifi\u00e9s sans pr\u00e9avis. Les frais de port sont en sus.   Sous r\u00e9serve d&rsquo;erreurs, de modifications de l&rsquo;\u00e9tendue de la livraison et de la conception, d&rsquo;erreurs d&rsquo;impression et de modifications de prix. Les prix barr\u00e9s sont plut\u00f4t des prix. L&rsquo;illustration peut diff\u00e9rer de l&rsquo;original\/de l&rsquo;\u00e9tendue de la livraison.<br \/>\n*Livraison gratuite pour les commandes sup\u00e9rieures \u00e0 CHF 250.-.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grinder Super Heroes noir 2 pi\u00e8ces &nbsp; mat\u00e9riel m\u00e9tal nombre de composants 2 parties diam\u00e8tre en mm 30 hauteur en mm 15 Tous les prix indiqu\u00e9s sont valables uniquement pour les commandes en ligne, TVA incluse, et peuvent \u00eatre modifi\u00e9s sans pr\u00e9avis. Les frais de port sont en sus. Sous r\u00e9serve d&rsquo;erreurs, de modifications de [&hellip;]<\/p>\n","protected":false},"featured_media":170215,"template":"","meta":[],"product_brand":[],"product_cat":[3219,2152,1995],"product_tag":[],"class_list":["post-170208","product","type-product","status-publish","has-post-thumbnail","product_cat-boutique-de-tete","product_cat-grinder-moulins","product_cat-divers-headshop-offres-speciales","first","instock","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grinder Super Heroes noir 2 pi\u00e8ces - tabakversand.ch<\/title>\n<meta name=\"description\" content=\"Grinder Super Heroes noir 2 pi\u00e8ces | Un tr\u00e8s grand choix de produits du tabac haut de gamme, d&#039;e-smoke et d&#039;accessoires pour fumeurs dans toute la Suisse | Cartes accept\u00e9es !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grinder Super Heroes noir 2 pi\u00e8ces - tabakversand.ch\" \/>\n<meta property=\"og:description\" content=\"Grinder Super Heroes noir 2 pi\u00e8ces | Un tr\u00e8s grand choix de produits du tabac haut de gamme, d&#039;e-smoke et d&#039;accessoires pour fumeurs dans toute la Suisse | Cartes accept\u00e9es !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/\" \/>\n<meta property=\"og:site_name\" content=\"Tabakversand.ch | Alles aus der Welt des Tabaks\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T12:09:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tabakversand.ch\/wp-content\/uploads\/2025\/02\/grinder-pocket-sized-340043-black.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/produit\\\/grinder-super-heroes-noir-2-pieces\\\/\",\"url\":\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/produit\\\/grinder-super-heroes-noir-2-pieces\\\/\",\"name\":\"Grinder Super Heroes noir 2 pi\u00e8ces - tabakversand.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tabakversand.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/produit\\\/grinder-super-heroes-noir-2-pieces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/produit\\\/grinder-super-heroes-noir-2-pieces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tabakversand.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/grinder-pocket-sized-340043-black.jpg\",\"datePublished\":\"2025-02-13T16:25:35+00:00\",\"dateModified\":\"2026-06-15T12:09:24+00:00\",\"description\":\"Grinder Super Heroes noir 2 pi\u00e8ces | Un tr\u00e8s grand choix de produits du tabac haut de gamme, d'e-smoke et d'accessoires pour fumeurs dans toute la Suisse | Cartes accept\u00e9es !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/produit\\\/grinder-super-heroes-noir-2-pieces\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/produit\\\/grinder-super-heroes-noir-2-pieces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/produit\\\/grinder-super-heroes-noir-2-pieces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tabakversand.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/grinder-pocket-sized-340043-black.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tabakversand.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/grinder-pocket-sized-340043-black.jpg\",\"width\":500,\"height\":500,\"caption\":\"Broyeur \u00e0 caf\u00e9 Super H\u00e9ros Noir, lot de 2 pi\u00e8ces | Tabakversand.ch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/produit\\\/grinder-super-heroes-noir-2-pieces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tabakversand.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.tabakversand.ch\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grinder Super Heroes noir 2 pi\u00e8ces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tabakversand.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.tabakversand.ch\\\/\",\"name\":\"Tabakversand.ch | Alles aus der Welt des Tabaks\",\"description\":\"Smoke and carpe diem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tabakversand.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grinder Super Heroes noir 2 pi\u00e8ces - tabakversand.ch","description":"Grinder Super Heroes noir 2 pi\u00e8ces | Un tr\u00e8s grand choix de produits du tabac haut de gamme, d'e-smoke et d'accessoires pour fumeurs dans toute la Suisse | Cartes accept\u00e9es !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/","og_locale":"fr_FR","og_type":"article","og_title":"Grinder Super Heroes noir 2 pi\u00e8ces - tabakversand.ch","og_description":"Grinder Super Heroes noir 2 pi\u00e8ces | Un tr\u00e8s grand choix de produits du tabac haut de gamme, d'e-smoke et d'accessoires pour fumeurs dans toute la Suisse | Cartes accept\u00e9es !","og_url":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/","og_site_name":"Tabakversand.ch | Alles aus der Welt des Tabaks","article_modified_time":"2026-06-15T12:09:24+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.tabakversand.ch\/wp-content\/uploads\/2025\/02\/grinder-pocket-sized-340043-black.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/","url":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/","name":"Grinder Super Heroes noir 2 pi\u00e8ces - tabakversand.ch","isPartOf":{"@id":"https:\/\/www.tabakversand.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/#primaryimage"},"image":{"@id":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tabakversand.ch\/wp-content\/uploads\/2025\/02\/grinder-pocket-sized-340043-black.jpg","datePublished":"2025-02-13T16:25:35+00:00","dateModified":"2026-06-15T12:09:24+00:00","description":"Grinder Super Heroes noir 2 pi\u00e8ces | Un tr\u00e8s grand choix de produits du tabac haut de gamme, d'e-smoke et d'accessoires pour fumeurs dans toute la Suisse | Cartes accept\u00e9es !","breadcrumb":{"@id":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/#primaryimage","url":"https:\/\/www.tabakversand.ch\/wp-content\/uploads\/2025\/02\/grinder-pocket-sized-340043-black.jpg","contentUrl":"https:\/\/www.tabakversand.ch\/wp-content\/uploads\/2025\/02\/grinder-pocket-sized-340043-black.jpg","width":500,"height":500,"caption":"Broyeur \u00e0 caf\u00e9 Super H\u00e9ros Noir, lot de 2 pi\u00e8ces | Tabakversand.ch"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tabakversand.ch\/fr\/produit\/grinder-super-heroes-noir-2-pieces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tabakversand.ch\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.tabakversand.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Grinder Super Heroes noir 2 pi\u00e8ces"}]},{"@type":"WebSite","@id":"https:\/\/www.tabakversand.ch\/#website","url":"https:\/\/www.tabakversand.ch\/","name":"Tabakversand.ch | Alles aus der Welt des Tabaks","description":"Smoke and carpe diem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tabakversand.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/product\/170208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":4,"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/product\/170208\/revisions"}],"predecessor-version":[{"id":220427,"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/product\/170208\/revisions\/220427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/media\/170215"}],"wp:attachment":[{"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/media?parent=170208"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=170208"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=170208"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tabakversand.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=170208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}